{"id":76,"date":"2013-08-19T19:35:32","date_gmt":"2013-08-19T19:35:32","guid":{"rendered":"http:\/\/localhost:8888\/test\/?page_id=670"},"modified":"2020-03-17T20:42:35","modified_gmt":"2020-03-17T20:42:35","slug":"message-box","status":"publish","type":"page","link":"https:\/\/mcpg.org.my\/v1\/elements\/message-box\/","title":{"rendered":"Message box"},"content":{"rendered":"\n  <div class=\"banner has-hover has-parallax\" id=\"banner-1761632357\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div><!-- bg-layers -->\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-330136143\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"2\" data-parallax-fade=\"true\">                  <div class=\"text \">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Message Box Element<\/strong><\/h2>\n<p class=\"lead\">Create beautiful Call to Action areas.<\/p>\n              <\/div>\n           <\/div><!-- text-box-inner -->\n              <\/div>              \n<style scope=\"scope\">\n\n#text-box-330136143 {\n  width: 60%;\n}\n#text-box-330136143 .text {\n  font-size: 100%;\n}\n<\/style>\n    <\/div><!-- text-box -->\n \n        <\/div><!-- .banner-layers -->\n      <\/div><!-- .banner-inner -->\n\n            \n<style scope=\"scope\">\n\n#banner-1761632357 {\n  padding-top: 500px;\n}\n#banner-1761632357 .bg.bg-loaded {\n  background-image: url(https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-2.jpg);\n}\n#banner-1761632357 .overlay {\n  background-color: rgba(255, 255, 255, 0.61);\n}\n#banner-1761632357 .bg {\n  background-position: 41% 71%;\n}\n<\/style>\n  <\/div><!-- .banner -->\n\n\n<div class=\"row\"  id=\"row-1073286851\">\n<div class=\"col small-12 large-12\"  ><div class=\"col-inner\"  >\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Message Box Element<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"message-box relative dark\" style=\"padding-top:27px;padding-bottom:27px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" ><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n<div class=\"row align-middle align-center\"  id=\"row-90167860\">\n<div class=\"col medium-9 small-12 large-9\"  ><div class=\"col-inner\"  >\n<p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n<\/div><\/div>\n<div class=\"col medium-2 small-12 large-2\"  ><div class=\"col-inner text-center\"  >\n<a class=\"button white is-outline\"  style=\"border-radius:99px;\">\n    <span>Click me<\/span>\n  <\/a>\n\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<\/div><\/div><\/div>\n<div class=\"container section-title-container\" style=\"margin-top:23px;\"><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Use to Create Call to Actions areas<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"message-box relative dark\" style=\"padding-top:27px;padding-bottom:27px;\"><div class=\"message-box-bg-image bg-fill fill\" style=\"background-image:url(https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-2.jpg);\"><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgba(0, 0, 0, 0.62);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n<div class=\"row align-middle align-center\"  id=\"row-127146880\">\n<div class=\"col medium-8 small-12 large-8\"  ><div class=\"col-inner\"  >\n<h2 class=\"uppercase\">Use Message Boxes to create Call to action messages<\/h2>\n<\/div><\/div>\n<div class=\"col medium-3 small-12 large-3\"  ><div class=\"col-inner text-center\"  >\n<a class=\"button white is-outline is-larger\"  style=\"border-radius:99px;\">\n    <span>Click me now<\/span>\n  <\/a>\n\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<div class=\"container section-title-container\" style=\"margin-top:23px;\"><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Full Width Message box<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"message-box relative dark\" style=\"padding-top:27px;padding-bottom:27px;\"><div class=\"message-box-bg-image bg-fill fill\" style=\"background-image:url(https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-2.jpg);\"><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgba(0, 0, 0, 0.75);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n<div class=\"row align-middle align-center\"  id=\"row-861161496\">\n<div class=\"col medium-6 small-15 large-6\"  ><div class=\"col-inner\"  >\n<h3 class=\"uppercase\">Signup for Newsletter and get <span class=\"fancy-underline\">50% off<\/span> your next purchase<\/h3>\n<\/div><\/div>\n<div class=\"col medium-5 small-17 large-5\"  ><div class=\"col-inner text-right\"  >\n<p>(insert contact form here)<\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":11,"parent":96,"menu_order":21,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-76","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":1,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"predecessor-version":[{"id":141,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/76\/revisions\/141"}],"up":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/96"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/media\/11"}],"wp:attachment":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}