{"id":80,"date":"2013-08-18T15:09:39","date_gmt":"2013-08-18T15:09:39","guid":{"rendered":"http:\/\/localhost:8888\/test\/?page_id=642"},"modified":"2020-03-17T20:42:35","modified_gmt":"2020-03-17T20:42:35","slug":"team-member","status":"publish","type":"page","link":"https:\/\/mcpg.org.my\/v1\/elements\/team-member\/","title":{"rendered":"Team Member"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-618434373\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div><!-- bg-layers -->\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-737568492\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>TEAM MEMBER ELEMENT<\/strong><\/h3>\n<p class=\"lead\">Use this for presenting your team member or staff<\/p>\n              <\/div>\n           <\/div><!-- text-box-inner -->\n                            \n<style scope=\"scope\">\n\n#text-box-737568492 {\n  width: 86%;\n}\n#text-box-737568492 .text {\n  font-size: 138%;\n}\n\n\n@media (min-width:550px) {\n\n  #text-box-737568492 {\n    width: 60%;\n  }\n  #text-box-737568492 .text {\n    font-size: 100%;\n  }\n\n}\n<\/style>\n    <\/div><!-- text-box -->\n \n        <\/div><!-- .banner-layers -->\n      <\/div><!-- .banner-inner -->\n\n            \n<style scope=\"scope\">\n\n#banner-618434373 {\n  padding-top: 395px;\n}\n#banner-618434373 .bg.bg-loaded {\n  background-image: url(https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-2.jpg);\n}\n#banner-618434373 .overlay {\n  background-color: rgba(0, 0, 0, 0.1);\n}\n<\/style>\n  <\/div><!-- .banner -->\n\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Default Style<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"row\"  id=\"row-2079882308\">\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CEO \/ FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CO FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"#\" data-open=\"#follow-snapchat-lightbox\" data-color=\"dark\" data-pos=\"center\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"SnapChat\" class=\"icon button circle is-outline snapchat tooltip\" title=\"Follow on SnapChat\"><i class=\"icon-snapchat\" ><\/i><\/a><div id=\"follow-snapchat-lightbox\" class=\"mfp-hide\"><div class=\"text-center\"><p>Point the SnapChat camera at this to add us to SnapChat.<\/p><\/div><\/div><a href=\"#\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:emailus@email.com\" data-label=\"E-mail\"  rel=\"nofollow\" class=\"icon button circle is-outline  email tooltip\" title=\"Send us an email\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"LinkedIn\" class=\"icon button circle is-outline  linkedin tooltip\" title=\"Follow on LinkedIn\"><i class=\"icon-linkedin\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Mark Jance<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CTO \/ Developer                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Nina Lacy<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      Support Ninja                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Color Icon style<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"row\"  id=\"row-456117639\">\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CEO \/ FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon primary button circle  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CO FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"#\" data-open=\"#follow-snapchat-lightbox\" data-color=\"dark\" data-pos=\"center\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"SnapChat\" class=\"icon primary button circle snapchat tooltip\" title=\"Follow on SnapChat\"><i class=\"icon-snapchat\" ><\/i><\/a><div id=\"follow-snapchat-lightbox\" class=\"mfp-hide\"><div class=\"text-center\"><p>Point the SnapChat camera at this to add us to SnapChat.<\/p><\/div><\/div><a href=\"#\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:emailus@email.com\" data-label=\"E-mail\"  rel=\"nofollow\" class=\"icon primary button circle  email tooltip\" title=\"Send us an email\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon primary button circle  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"LinkedIn\" class=\"icon primary button circle  linkedin tooltip\" title=\"Follow on LinkedIn\"><i class=\"icon-linkedin\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Mark Jance<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CTO \/ Developer                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon primary button circle  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Nina Lacy<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      Support Ninja                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon primary button circle  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Bounce Style<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"row\"  id=\"row-521579861\">\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-bounce box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CEO \/ FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-bounce box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CO FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"#\" data-open=\"#follow-snapchat-lightbox\" data-color=\"dark\" data-pos=\"center\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"SnapChat\" class=\"icon button circle is-outline snapchat tooltip\" title=\"Follow on SnapChat\"><i class=\"icon-snapchat\" ><\/i><\/a><div id=\"follow-snapchat-lightbox\" class=\"mfp-hide\"><div class=\"text-center\"><p>Point the SnapChat camera at this to add us to SnapChat.<\/p><\/div><\/div><a href=\"#\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:emailus@email.com\" data-label=\"E-mail\"  rel=\"nofollow\" class=\"icon button circle is-outline  email tooltip\" title=\"Send us an email\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"LinkedIn\" class=\"icon button circle is-outline  linkedin tooltip\" title=\"Follow on LinkedIn\"><i class=\"icon-linkedin\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-bounce box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Mark Jance<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CTO \/ Developer                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-bounce box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Nina Lacy<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      Support Ninja                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Push Style<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"row\"  id=\"row-440282986\">\n<div class=\"col medium-4 large-4\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-push box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text show-on-hover hover-bounce text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CEO \/ FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-4 large-4\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-push box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text show-on-hover hover-bounce text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Mark Jance<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CTO \/ Developer                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<div class=\"col medium-4 large-4\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-push box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                         <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text show-on-hover hover-bounce text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Nina Lacy<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      Support Ninja                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                 \n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<\/div><\/div>\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Overlay Style<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"row\"  id=\"row-727300887\">\n<div class=\"col medium-4 large-4\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CEO \/ FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-4 large-4\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CO FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"#\" data-open=\"#follow-snapchat-lightbox\" data-color=\"dark\" data-pos=\"center\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"SnapChat\" class=\"icon button circle is-outline snapchat tooltip\" title=\"Follow on SnapChat\"><i class=\"icon-snapchat\" ><\/i><\/a><div id=\"follow-snapchat-lightbox\" class=\"mfp-hide\"><div class=\"text-center\"><p>Point the SnapChat camera at this to add us to SnapChat.<\/p><\/div><\/div><a href=\"#\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:emailus@email.com\" data-label=\"E-mail\"  rel=\"nofollow\" class=\"icon button circle is-outline  email tooltip\" title=\"Send us an email\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"LinkedIn\" class=\"icon button circle is-outline  linkedin tooltip\" title=\"Follow on LinkedIn\"><i class=\"icon-linkedin\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-4 large-4\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Mark Jance<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CTO \/ Developer                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n<\/div>\n    \n<\/div><\/div>\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Overlay Circle<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"row\"  id=\"row-1372608023\">\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CEO \/ FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CO FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"#\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:emailus@email.com\" data-label=\"E-mail\"  rel=\"nofollow\" class=\"icon button circle is-outline  email tooltip\" title=\"Send us an email\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"LinkedIn\" class=\"icon button circle is-outline  linkedin tooltip\" title=\"Follow on LinkedIn\"><i class=\"icon-linkedin\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Mark Jance<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CTO \/ Developer                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image \" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Nina Lacy<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      Support Ninja                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ullamcorper<\/p>\n<\/div>\n    \n<\/div><\/div>\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Overlay Grayscale<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"row\"  id=\"row-2138405284\">\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image image-color\" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CEO \/ FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image image-color\" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CO FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"#\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:emailus@email.com\" data-label=\"E-mail\"  rel=\"nofollow\" class=\"icon button circle is-outline  email tooltip\" title=\"Send us an email\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"LinkedIn\" class=\"icon button circle is-outline  linkedin tooltip\" title=\"Follow on LinkedIn\"><i class=\"icon-linkedin\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image image-color\" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Mark Jance<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CTO \/ Developer                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image image-color\" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Nina Lacy<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      Support Ninja                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<\/div>\n    \n<\/div><\/div>\n<\/div>\n\t<section class=\"section dark\" id=\"section_384955159\">\n\t\t<div class=\"bg section-bg fill bg-fill  \" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div><!-- .section-bg -->\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Mix and match styles<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n<div class=\"row\"  id=\"row-189743923\">\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image image-color image-zoom\" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CEO \/ FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon plain facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon plain  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon plain  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image image-glow\" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:9%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Lucy Anderson<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CO FOUNDER                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"#\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:emailus@email.com\" data-label=\"E-mail\"  rel=\"nofollow\" class=\"icon primary button circle  email tooltip\" title=\"Send us an email\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-label=\"LinkedIn\" class=\"icon primary button circle  linkedin tooltip\" title=\"Follow on LinkedIn\"><i class=\"icon-linkedin\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image image-zoom\" >\n           <div class=\"box-image-inner image-cover\" style=\"padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Mark Jance<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      CTO \/ Developer                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon button circle is-outline  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon button circle is-outline  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<\/div>\n    \n<\/div><\/div>\n<div class=\"col medium-3 large-3\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-overlay dark box-text-bottom\" >\n\n                  <div class=\"box-image image-color\" >\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0,0,0,.2)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Nina Lacy<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                      Support Ninja                    <\/span>\n                  <\/h4>\n                 <div class=\"social-icons follow-icons \" ><a href=\"uxthemes\" target=\"_blank\" data-label=\"Facebook\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle facebook tooltip\" title=\"Follow on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"http:\/\/twitter.com\/uxthemes\" target=\"_blank\"  data-label=\"Twitter\"  rel=\"noopener noreferrer nofollow\" class=\"icon primary button circle  twitter tooltip\" title=\"Follow on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"http:\/\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"  data-label=\"Pinterest\"  class=\"icon primary button circle  pinterest tooltip\" title=\"Follow on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>                                 <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    <div class=\"team-member-content pt-half text-center\">\n<\/div>\n    \n<\/div><\/div>\n<\/div>\n\t\t<\/div><!-- .section-content -->\n\n\t\t\n<style scope=\"scope\">\n\n#section_384955159 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(40, 40, 40);\n}\n#section_384955159 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.84);\n}\n#section_384955159 .section-bg.bg-loaded {\n  background-image: url(https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-2.jpg);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":11,"parent":96,"menu_order":26,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-80","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":1,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/80\/revisions"}],"predecessor-version":[{"id":145,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/80\/revisions\/145"}],"up":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/96"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/media\/11"}],"wp:attachment":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}