{"id":96,"date":"2013-08-09T22:37:13","date_gmt":"2013-08-09T22:37:13","guid":{"rendered":"http:\/\/localhost:8888\/test\/?page_id=288"},"modified":"2013-08-09T22:37:13","modified_gmt":"2013-08-09T22:37:13","slug":"elements","status":"publish","type":"page","link":"https:\/\/mcpg.org.my\/v1\/elements\/","title":{"rendered":"Elements"},"content":{"rendered":"\t<section class=\"section\" id=\"section_1067082844\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:2px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div><!-- .section-bg -->\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row align-center\"  id=\"row-1333764509\">\r\n\r\n<div class=\"col medium-9 small-12 large-9\"  ><div class=\"col-inner text-center\"  >\r\n<h1 class=\"lead uppercase\">Flatsome Elements<\/h1>\r\n<p class=\"lead\">Flatsome is more than a theme. It's a framework for creating amazing Websites. Here is a collection of our highly customisable elements.<\/p>\r\n<\/div><\/div>\r\n<div class=\"col large-12\"  ><div class=\"col-inner\"  >\r\n\r\n\n  \n    <div class=\"row large-columns-8 medium-columns-3 small-columns-2 row-small has-shadow row-box-shadow-1 row-box-shadow-1-hover\">\n          <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/sections\/\" title=\"Sections\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Sections<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/rows-columns\/\" title=\"Rows \/ Columns\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Rows \/ Columns<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/sliders\/\" title=\"Sliders\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Sliders<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/banner\/\" title=\"Banners\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Banners<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/typography\/\" title=\"Typography\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Typography<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/buttons\/\" title=\"Buttons\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Buttons<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/titles-dividers\/\" title=\"Titles \/ Dividers\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Titles \/ Dividers<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/blog-posts\/\" title=\"Blog Posts\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Blog Posts<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/images\/\" title=\"Images\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Images<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/video\/\" title=\"Video\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Video<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/galleries\/\" title=\"Galleries\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Galleries<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/video-button\/\" title=\"Video Button\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Video Button<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/banner-grid\/\" title=\"Banner Grids\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Banner Grids<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/icon-box\/\" title=\"Icon Box\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Icon Box<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/image-box\/\" title=\"Image Box\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Image Box<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/lightbox\/\" title=\"Lightbox\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Lightbox<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/scroll-to\/\" title=\"Scroll To\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Scroll To<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/\" title=\"Pages\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Pages<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/left-sidebar\/\" title=\"Left Sidebar\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                                            <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Left Sidebar<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/maintenance\/\" title=\"Maintenance\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                                            <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Maintenance<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/size-chart\/\" title=\"Size Chart\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                                            <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Size Chart<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/contact\/\" title=\"Contact\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Contact<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/about\/\" title=\"About\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>About<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/about-2\/\" title=\"Objectives\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Objectives<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/management\/\" title=\"Management\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Management<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/issues-action\/\" title=\"Issues & Action\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Issues & Action<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/practice-support\/\" title=\"Practice Support\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Practice Support<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/good-pharmaceutical-trading-practices-gptp\/\" title=\"Good Pharmaceutical Trading Practices (GPTP)\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Good Pharmaceutical Trading Practices (GPTP)<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/illegal-sales-of-medicine-iosm\/\" title=\"Illegal Sales Of Medicine (IOSM)\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Illegal Sales Of Medicine (IOSM)<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/gptp-online-reporting\/\" title=\"GPTP Online Reporting\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>GPTP Online Reporting<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/membership\/\" title=\"Membership\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Membership<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/banking-information\/\" title=\"Banking Information\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Banking Information<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/be-a-member\/\" title=\"Be A Member\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Be A Member<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/be-a-member-returning-member\/\" title=\"Returning Member\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Returning Member<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/pages\/portfolio\/\" title=\"Portfolio\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Portfolio<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/map\/\" title=\"Map\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Map<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/message-box\/\" title=\"Message box\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Message box<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/product-categories\/\" title=\"Product Categories\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Product Categories<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/products\/\" title=\"Products\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Products<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/sharefollow-icons\/\" title=\"Share \/ follow icons\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Share \/ follow icons<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/tabs\/\" title=\"Tabs\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Tabs<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/team-member\/\" title=\"Team Member\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Team Member<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/testemonials\/\" title=\"Testimonials\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Testimonials<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/countdown\/\" title=\"Countdown\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Countdown<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/flip-book\/\" title=\"Flip Book\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Flip Book<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/hotspot\/\" title=\"Hotspot\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Hotspot<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/forms\/\" title=\"Forms\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Forms<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/price-table\/\" title=\"Price table\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Price table<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/search-box\/\" title=\"Search box\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Search box<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/instagram-feed\/\" title=\"Instagram feed\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Instagram feed<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/accordion\/\" title=\"Accordion\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Accordion<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n                 <div class=\"page-col col\" >\n          <div class=\"col-inner\" >\n          <a class=\"plain\" href=\"https:\/\/mcpg.org.my\/v1\/elements\/logo\/\" title=\"Logo\" target=\"\">\n            <div class=\"page-box box has-hover box-default\">\n                  <div class=\"box-image\" >\n                      <div class=\"box-image image-zoom image-cover\" style=\"padding-top:68%;\">\n                      <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/mcpg.org.my\/v1\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                      <\/div><!-- image -->\n                                                              <\/div><!-- box-image -->\n                  <div class=\"box-text text-left\" style=\"background-color:rgb(250, 250, 250);padding:1px 1px 3px 10px;\">\n                        <div class=\"box-text-inner\">\n                            <p>Logo<\/p>\n                        <\/div><!-- box-text-inner -->\n                  <\/div><!-- box-text -->\n              <\/div><!-- .image-box .box -->\n            <\/a>\n            <\/div><!-- .col-inner -->\n          <\/div><!-- .col -->\n         <\/div>\r\n\r\n<\/div><\/div>\r\n\r\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\r\n\r\n\t\t<\/div><!-- .section-content -->\n\n\t\t\n<style scope=\"scope\">\n\n#section_1067082844 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(250, 250, 250);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":11,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-96","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":0,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/pages\/96\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/media\/11"}],"wp:attachment":[{"href":"https:\/\/mcpg.org.my\/v1\/wp-json\/wp\/v2\/media?parent=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}